{"id":73496,"date":"2020-02-29T01:04:31","date_gmt":"2020-02-29T00:04:31","guid":{"rendered":"http:\/\/www.sagnature.it\/public\/wordpress\/prodotto\/richiamo-acme-a-fiato-per-corvo-e-cornacchia\/"},"modified":"2026-05-05T16:39:37","modified_gmt":"2026-05-05T14:39:37","slug":"richiamo-acme-a-fiato-per-corvo-e-cornacchia","status":"publish","type":"product","link":"https:\/\/www.sagnature.it\/public\/wordpress\/prodotto\/richiamo-acme-a-fiato-per-corvo-e-cornacchia\/","title":{"rendered":"0805014 &#8211; RICHIAMO ACME A FIATO PER CORVO E CORNACCHIA  &#8211; MODEL 259"},"content":{"rendered":"<p> <a target=\"_blank\" href=\"http:\/\/www.sagnature.it\/0listino\/EXCEL\/phpNativoCVS\/ArticoloGet.php?ARTICOLO=0805014\"> CLICCA QUI PER ULTERIORI DETTAGLI  <\/a> <\/p>\n<p><audio controls>    Your browser does not support the audio element.<\/audio><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLICCA QUI PER ULTERIORI DETTAGLI Your browser does not support the audio element.<\/p>\n","protected":false},"featured_media":125870,"template":"","meta":[],"product_brand":[],"product_cat":[1714,1715],"product_tag":[],"class_list":{"0":"post-73496","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-richiami-a-fiato","7":"product_cat-richiami-a-fiato-richiami-a-fiato","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/product\/73496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/media\/125870"}],"wp:attachment":[{"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/media?parent=73496"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/product_brand?post=73496"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/product_cat?post=73496"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sagnature.it\/public\/wordpress\/wp-json\/wp\/v2\/product_tag?post=73496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}